{"id":3530,"date":"2022-11-28T22:01:17","date_gmt":"2022-11-29T01:01:17","guid":{"rendered":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/?p=3530"},"modified":"2022-11-28T22:01:19","modified_gmt":"2022-11-29T01:01:19","slug":"abogacia-por-el-desarrollo-de-la-medicina-familiar-participa-en-grupo-de-trabajo-wonca","status":"publish","type":"post","link":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/2022\/11\/28\/abogacia-por-el-desarrollo-de-la-medicina-familiar-participa-en-grupo-de-trabajo-wonca\/","title":{"rendered":"Abogac\u00eda por el desarrollo de la Medicina Familiar: participa en grupo de trabajo WONCA"},"content":{"rendered":"<p style=\"text-align: justify;\">Special Interest Group: Policy Advocacy, es el grupo que integra la coordinadora de la Sociedad Chilena de Medicina Familiar, Dra. Carolina Posada, el cual se reunir\u00e1 este pr\u00f3ximo 1 de diciembre de 2022, y en la que los interesados ya pueden inscribirse.<\/p>\n<p style=\"text-align: justify;\">La invitaci\u00f3n a participar de esta actividad en l\u00ednea, seg\u00fan explica la Dra. Posada, es para contribuir a la promoci\u00f3n de pol\u00edticas p\u00fablicas hacia el desarrollo de la Medicina Familiar. \u00a0\u201cEs un grupo que est\u00e1 en formaci\u00f3n, comenzando a tirar sus primeras l\u00edneas. El objetivo inicial es reunir informaci\u00f3n y experiencias para poder llevarlas a la realidad de cada uno, para abogar por la Medicina Familia en pol\u00edticas p\u00fablicas, lo que se complementa con la labor que se desarrolla en la Sociedad Chilena de Medicina Familiar a trav\u00e9s del Comit\u00e9 de Abogac\u00eda. Yo particip\u00e9 en la primera actividad online que fue en septiembre, en la que b\u00e1sicamente se present\u00f3 la idea general y experiencias de algunos colegas\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">No es requisito integrar el Comit\u00e9 de Abogac\u00eda de la Sociedad Chilena de Medicina Familiar para inscribirse en este grupo de trabajo WONCA y quienes participen, ser\u00e1n invitados a compartir la experiencia, con tal de avanzar en esta misma \u00e1rea en Chile.<\/p>\n<p style=\"text-align: justify;\"><strong>Comit\u00e9 de Abogac\u00eda de la Sociedad Chilena de Medicina Familiar<\/strong><br \/>\nEl comit\u00e9 de Abogac\u00eda de la Sociedad Chilena de Medicina Familiar trabaja para optimizar la abogac\u00eda por la Medicina Familiar en Chile y sus l\u00edneas de trabajo son hacia integrar la especialidad desde los programas de pregrado en Facultades de Medicina, posicionar M\u00e9dicos de Familia como referentes en puestos directivos, tanto en APS como a nivel de servicios de salud o central, y aumentar la visibilidad de la especialidad en la opini\u00f3n p\u00fablica.\u00a0 Adem\u00e1s, relevar que los M\u00e9dicos de Familia, a trav\u00e9s de su labor en centros secundarios o terciarios, ejercen abogac\u00eda por la Estrategia de Atenci\u00f3n Primaria y la especialidad en general.<\/p>\n<p>Jueves 1 de diciembre 2022, pr\u00f3xima reuni\u00f3n de trabajo <strong>Special Interest Group: Policy Advocacy<\/strong><\/p>\n<p><strong>HORARIO: 12:00 \u2013 14:00 HORAS CHILE, v\u00eda ZOOM<\/strong><\/p>\n<p>Para acceder a mayor informaci\u00f3n sobre Special Interest Group: Policy Advocacy, puede acceder a este enlace: <a href=\"https:\/\/www.globalfamilydoctor.com\/groups\/SpecialInterestGroups\/PolicyAdvocacy.aspx\">https:\/\/www.globalfamilydoctor.com\/groups\/SpecialInterestGroups\/PolicyAdvocacy.aspx<\/a><\/p>\n<p>Link de inscripci\u00f3n: <a href=\"https:\/\/www.globalfamilydoctor.com\/groups\/SpecialInterestGroups\/PolicyAdvocacy\/JoinPolicyAdvocacySIG\">https:\/\/www.globalfamilydoctor.com\/groups\/SpecialInterestGroups\/PolicyAdvocacy\/JoinPolicyAdvocacySIG<\/a><\/p>\n<p>Para inscribirse a <strong>Comit\u00e9 de Abogac\u00eda SOCHIMEF<\/strong> acceda a este enlace: <a href=\"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/inscripcion-comites-sochimef\/\">http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/inscripcion-comites-sochimef\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>.<\/p>\n","protected":false},"author":1,"featured_media":3532,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[764,767,25,18,766,765,8],"class_list":["post-3530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-portada","tag-abogacia-mf","tag-comite-de-abogacia","tag-medicina-familiar","tag-mf","tag-policy-advocacy","tag-special-interest-group","tag-wonca"],"_links":{"self":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/3530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/comments?post=3530"}],"version-history":[{"count":1,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/3530\/revisions"}],"predecessor-version":[{"id":3531,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/3530\/revisions\/3531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/media\/3532"}],"wp:attachment":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/media?parent=3530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/categories?post=3530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/tags?post=3530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}