{"id":2809,"date":"2022-03-30T19:26:23","date_gmt":"2022-03-30T22:26:23","guid":{"rendered":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/?p=2809"},"modified":"2022-03-30T19:26:52","modified_gmt":"2022-03-30T22:26:52","slug":"dra-sandra-paredes-presidenta-xxiii-congreso-sochimef-el-recurso-humano-es-el-capital-mas-importante-que-tenemos-en-salud","status":"publish","type":"post","link":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/2022\/03\/30\/dra-sandra-paredes-presidenta-xxiii-congreso-sochimef-el-recurso-humano-es-el-capital-mas-importante-que-tenemos-en-salud\/","title":{"rendered":"Dra. Sandra Paredes, presidenta XXIII Congreso SOCHIMEF: \u201cEl recurso humano es el capital m\u00e1s importante que tenemos en salud\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Nuestra socia y presidenta de la versi\u00f3n 2022 del Congreso de Medicina Familiar organizado por la Sociedad Chilena de Medicina Familiar, nos entrega detalles del avance en la planificaci\u00f3n para el encuentro virtual desde Coyhaique cuyo lema es \u201cPersonas Cuidando a Personas\u201d.<\/strong><\/p>\n<p><em><strong>Por Andrea del Pilar G\u00f3mez&nbsp;<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\u201c\u00bfEn qu\u00e9 nos inspiramos para este lema? Las grandes crisis sanitarias y problemas cr\u00f3nicos de salud no se enfrentan solamente con infraestructura m\u00e9dica y recursos econ\u00f3micos, sino que el capital humano&nbsp; es y siempre ha sido, el valor m\u00e1s importante que tenemos en el sector salud. Por lo tanto, es relevante no s\u00f3lo darnos cuenta de eso, sino que tambi\u00e9n dar a conocer lo trascendente de su funci\u00f3n y tambi\u00e9n hacer conciencia de que debemos cuidarlo, identificando estrategias para promover el cuidado del recurso en general\u201d, comenta la Dra. Sandra Paredes, M\u00e9dica de Familia y presidenta del XXIII Congreso de Medicina Familiar, Personas Cuidando a Personas.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan revela la Dra. Paredes desde Coyhaique, sede de la pr\u00f3xima versi\u00f3n de nuestro Congreso 2022, \u201ceste lema marca el sello del Congreso, cuyo objetivo es poder revisar experiencias, o plantear algunos estudios que hay en relaci\u00f3n a problem\u00e1ticas vigentes y otras emergentes, por ejemplo, como se han enfrentado las enfermedades infecto contagiosa como el Hanta o el Covid-19. Pero tambi\u00e9n ver qu\u00e9 est\u00e1 pasando con los equipos de trabajo. C\u00f3mo cuidamos, validamos, mantenemos la importancia de las personas y su quehacer en salud. Esto siempre ha estado en el discurso, pero sentimos que hay que ir un paso m\u00e1s: buscando y mostrando nuevas estrategias para valorar, potenciar y cuidar nuestras personas.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Jornada Buenas Pr\u00e1cticas<\/em><\/strong><br \/>\nEl Congreso se desarrollar\u00e1 en formato virtual desde el 17 al 19 de noviembre 2022, a lo que se suma una Jornada previa de Buenas Pr\u00e1cticas que se desarrollar\u00e1 una semana antes, de manera presencial en la capital de la Regi\u00f3n de Ays\u00e9n. Esta Jornada tendr\u00e1 como objetivo poder convocar y concentrar a los distintos asistentes del resto de la regi\u00f3n que podr\u00edan trasladarse hasta Coyhaique, y &nbsp;compartir experiencias de Buenas Pr\u00e1cticas, ya sea en el cuidado de nuestro recurso humano, en c\u00f3mo se ha manejado la organizaci\u00f3n de los equipos de trabajo, temas que est\u00e1n siendo relevantes en los \u00faltimos meses. Nuestros expositores locales tendr\u00e1n la opci\u00f3n de compartir experiencias con los equipos del resto del pa\u00eds, dado que las mejores experiencias o trabajos, ser\u00e1n elegidas para ser presentadas en el Congreso virtual. Esto es bastante novedoso e interesante, porque nos permite tambi\u00e9n que nuestros colegas y compa\u00f1eros de trabajo locales puedan mostrar un poco de lo que hacemos ac\u00e1 y la realidad que vivimos. Yo creo que es una instancia de conocer, recopilar informaci\u00f3n, que se generen la opci\u00f3n de intercambio de experiencias y vivencias en el Congreso\u201d, detalla la presidenta del Congreso.<\/p>\n<p style=\"text-align: justify;\"><strong><em>Convocatoria abierta<br \/>\n<\/em><\/strong>\u201cNuestra idea es convocar no solamente a M\u00e9dicos de Familia, o de Atenci\u00f3n Primaria, sino que obviamente a todo el equipo que tiene mucho que compartir y son parte fundamental del trabajo. As\u00ed que incluso estamos pensando en armar alguna experiencia novedosa tambi\u00e9n en el contexto del trabajo con la comunidad, como alg\u00fan representante de los vecinos entre los invitados\u201d, adelanta la Dra. Sandra Paredes.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s informaci\u00f3n sobre XXIII Congreso de Medicina Familiar en el sgte link: <a href=\"http:\/\/congresomedicinafamiliar.cl\/mf\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/congresomedicinafamiliar.cl\/mf\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>.<\/p>\n","protected":false},"author":1,"featured_media":2813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,2,3],"tags":[676,14,677,674,273,25,166,675],"class_list":["post-2809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-congreso","category-noticias","category-portada","tag-personas-cuidando-a-personas","tag-aps","tag-congreso-mf-2022","tag-dra-sandra-paredes","tag-entrevista","tag-medicina-familiar","tag-mfcl","tag-xxiii-congres-sochimef"],"_links":{"self":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/2809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/comments?post=2809"}],"version-history":[{"count":4,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/2809\/revisions"}],"predecessor-version":[{"id":2815,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/2809\/revisions\/2815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/media\/2813"}],"wp:attachment":[{"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/media?parent=2809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/categories?post=2809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/tags?post=2809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}