{"id":3180,"date":"2022-07-26T19:03:13","date_gmt":"2022-07-26T22:03:13","guid":{"rendered":"https:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/?p=3180"},"modified":"2022-07-26T19:04:41","modified_gmt":"2022-07-26T22:04:41","slug":"dr-jorge-lopez-en-cada-persona-mayor-podemos-apreciar-como-los-determinantes-sociales-de-la-salud-dejan-su-impronta","status":"publish","type":"post","link":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/2022\/07\/26\/dr-jorge-lopez-en-cada-persona-mayor-podemos-apreciar-como-los-determinantes-sociales-de-la-salud-dejan-su-impronta\/","title":{"rendered":"Dr. Jorge L\u00f3pez. \u201cEn cada persona mayor podemos apreciar c\u00f3mo los determinantes sociales de la salud dejan su impronta\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">En ciclo de entrevistas organizado por el coordinador del comit\u00e9 Persona Mayor de SOCHIMEF, Dr. Andr\u00e9s Glasinovic, el integrante de esta instancia y vicepresidente de nuestra Sociedad Chilena de Medicina Familiar, responde sobre su experiencia.<\/p>\n<p><em><strong>Edici\u00f3n Andrea del Pilar Gomez<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">El doctor Jorge Alejandro L\u00f3pez G\u00e1lvez cuenta con 15 a\u00f1os de experiencia en Atenci\u00f3n Primaria de Salud. Actualmente trabaja en el Centro de Salud Familiar Alerce y Departamento de Salud Municipal de Puerto Montt. Asimismo, es M\u00e9dico de Familia de atenci\u00f3n privada en Cl\u00ednica Puerto Varas, y docente de pregrado en la carrera de medicina y en el Programa de Especializaci\u00f3n de Medicina Familiar en la Universidad San Sebasti\u00e1n, Sede Patagonia.<\/p>\n<p><em>&#8211; \u00bfC\u00f3mo describe su experiencia en el trabajo con personas mayores?<\/em><\/p>\n<p style=\"text-align: justify;\">&#8211; \u201cRealizo atenciones de morbilidad y patolog\u00eda cr\u00f3nica en consulta privada. A su vez, realizo visita domiciliaria integral a personas con dependencia severa en CESFAM. En ambos casos la experiencia es siempre enriquecedora, generando v\u00ednculos con mis pacientes y buscando en cada atenci\u00f3n aportar en una mejor calidad de vida, buscando reducir polifarmacia, promover conductas saludables, o a veces tan solo acompa\u00f1ar\u201d.<\/p>\n<p>&#8211; \u00bf<em>Cu\u00e1les con los principales aprendizajes de vida en la atenci\u00f3n a este grupo?<\/em><\/p>\n<p style=\"text-align: justify;\">&#8211; \u201cEn cada persona mayor podemos apreciar c\u00f3mo los determinantes sociales de la salud dejan su impronta. Por ejemplo, las realidades en cuanto a prevalencia y compensaci\u00f3n de patolog\u00edas cr\u00f3nicas, fragilidad, sedentarismo, obesidad son diametralmente distintas entre personas mayores con bajo nivel de estudios versus aquellos que han alcanzado estudios superiores. Incluso con ingresos similares, personas mayores con estudios superiores logran acceder con m\u00e1s facilidad a toda la oferta de prestaciones que se les brinda a nivel municipal o estatal\u201d.<\/p>\n<p style=\"text-align: justify;\">El Dr. L\u00f3pez agreg\u00f3 como aprendizajes relevantes en el trabajo con las Personas Mayores, que \u201clas limitaciones funcionales no tienen que necesariamente determinar no poder llevar una vida satisfactoria: \u00a1he podido conocer historias fant\u00e1sticas de superaci\u00f3n y resiliencia que son ejemplos de vida para todo quien quiera escucharlas!. El apoyo social es un factor protector fundamental para una mejor vejez, y por tanto debemos promoverlo activamente. En esta l\u00ednea, frente a conflictos en relaci\u00f3n a los cuidados de personas mayores es muy importante limitar nuestros prejuicios y comprender que podemos estar frente a historias de vida complejas, secretos familiares, historias de abandono o abuso que generan grandes dificultades para los cuidadores, quienes requieren de nuestro apoyo y comprensi\u00f3n\u201d.<\/p>\n<p>&#8211; <em>Desde ese punto, \u00bfcu\u00e1les son a su juicio, los principales desaf\u00edos en la atenci\u00f3n del adulto mayor?<\/em><\/p>\n<p style=\"text-align: justify;\">&#8211; El Dr. Jorge L\u00f3pez apunta como elementos de exigencia en la atenci\u00f3n a la Persona Mayor, \u201clas redes sociales fr\u00e1giles o ausentes, o el manejo de la sobrecarga del cuidador resultan ser problem\u00e1ticas cuyo enfrentamiento considera junto a nuestro rol como equipos de salud, la implementaci\u00f3n de pol\u00edticas p\u00fablicas dirigidas a garantizar un cuidado digno. Por otro lado, existen m\u00faltiples desaf\u00edos en el primer nivel de atenci\u00f3n, como por ejemplo, el manejo no farmacol\u00f3gico de las demencias por equipos de salud, o la aplicaci\u00f3n efectiva de la ley de atenci\u00f3n preferente a personas mayores y con discapacidad.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>.<\/p>\n","protected":false},"author":1,"featured_media":3182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[285,2,3],"tags":[14,450,25,24],"class_list":["post-3180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista","category-noticias","category-portada","tag-aps","tag-dr-jorge-lopez","tag-medicina-familiar","tag-sochimef"],"_links":{"self":[{"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/3180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/comments?post=3180"}],"version-history":[{"count":3,"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/3180\/revisions"}],"predecessor-version":[{"id":3184,"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/posts\/3180\/revisions\/3184"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/media\/3182"}],"wp:attachment":[{"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/media?parent=3180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/categories?post=3180"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.medicinafamiliar.cl\/mf\/wordpress\/wp-json\/wp\/v2\/tags?post=3180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}